{"id":23569,"date":"2021-09-09T21:07:20","date_gmt":"2021-09-10T00:07:20","guid":{"rendered":"https:\/\/maranhaotv.com.br\/?p=23569"},"modified":"2021-09-09T21:07:20","modified_gmt":"2021-09-10T00:07:20","slug":"maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra","status":"publish","type":"post","link":"https:\/\/maranhaotv.com.br\/index.php\/2021\/09\/09\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\/","title":{"rendered":"Maura Jorge cobra da Caema provid\u00eancias sobre falta de \u00e1gua em bairros de Lago da Pedra"},"content":{"rendered":"\n<p>Maura Jorge cobra da Caema <br>A  prefeita de Lago da Pedra   Maura Jorge vem cobrando providencias da CAEMA, sobre a situa\u00e7\u00e3o de abastecimento de \u00e1gua da cidade, mesmo n\u00e3o sendo uma responsabilidade direta do governo municipal.<br><br>Maura Jorge solicitou da Companhia, provid\u00eancias a respeito da capta\u00e7\u00e3o, tratamento e distribui\u00e7\u00e3o de \u00e1gua dos bairros afetados, o quanto antes e definitivamente, pois os moradores v\u00eam sofrendo com falta de \u00e1gua a duas semanas.<br><br>Em resposta a preferia de Lago da Pedra a CAEMA-Companhia de Saneamento Ambiental do Maranh\u00e3o. Informou que as providencias j\u00e1 est\u00e3o sendo tomadas, esclarecendo a popula\u00e7\u00e3o que os po\u00e7os s\u00e3o de 300 metros. Por isso a dificuldade quando queima a bomba, encontramos dificuldade para  compra. E que hoje a equipe de manuten\u00e7\u00e3o estar\u00e1 se deslocando para  Lago da Pedra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maura Jorge cobra da Caema A prefeita de Lago da Pedra Maura Jorge vem cobrando providencias da CAEMA, sobre a<\/p>\n","protected":false},"author":2,"featured_media":23568,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-23569","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"magazineBlocksPostFeaturedMedia":{"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"colormag-highlighted-post":false,"colormag-featured-post-medium":false,"colormag-featured-post-small":false,"colormag-featured-image":false,"colormag-default-news":false,"colormag-featured-image-large":false},"magazineBlocksPostAuthor":{"name":"maranhaotv","avatar":"https:\/\/secure.gravatar.com\/avatar\/8fadbca458d4cb68b1dd399ae9a40618d747bb1af65ac9fad21c89220a143eb4?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":"0","magazineBlocksPostExcerpt":"Maura Jorge cobra da Caema A prefeita de Lago da Pedra Maura Jorge vem cobrando providencias da CAEMA, sobre a","magazineBlocksPostCategories":["pol\u00edtica"],"magazineBlocksPostViewCount":139,"magazineBlocksPostReadTime":1,"magazine_blocks_featured_image_url":{"full":false,"medium":false,"thumbnail":false},"magazine_blocks_author":{"display_name":"maranhaotv","author_link":"https:\/\/maranhaotv.com.br\/index.php\/author\/maranhaotv\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/8fadbca458d4cb68b1dd399ae9a40618d747bb1af65ac9fad21c89220a143eb4?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-6\">pol\u00edtica<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Maura Jorge cobra da Caema provid\u00eancias sobre falta de \u00e1gua em bairros de Lago da Pedra - NOT\u00cdCIAS EM TEMPO REAL<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maranhaotv.com.br\/index.php\/2021\/09\/09\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maura Jorge cobra da Caema provid\u00eancias sobre falta de \u00e1gua em bairros de Lago da Pedra - NOT\u00cdCIAS EM TEMPO REAL\" \/>\n<meta property=\"og:description\" content=\"Maura Jorge cobra da Caema A prefeita de Lago da Pedra Maura Jorge vem cobrando providencias da CAEMA, sobre a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maranhaotv.com.br\/index.php\/2021\/09\/09\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\/\" \/>\n<meta property=\"og:site_name\" content=\"NOT\u00cdCIAS EM TEMPO REAL\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/maiobaotv\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-10T00:07:20+00:00\" \/>\n<meta name=\"author\" content=\"maranhaotv\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sitemaranhaotv\" \/>\n<meta name=\"twitter:site\" content=\"@sitemaranhaotv\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"maranhaotv\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/09\\\/09\\\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/09\\\/09\\\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\\\/\"},\"author\":{\"name\":\"maranhaotv\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#\\\/schema\\\/person\\\/3d54238e86b20bb5c89ab2fdb8f8829a\"},\"headline\":\"Maura Jorge cobra da Caema provid\u00eancias sobre falta de \u00e1gua em bairros de Lago da Pedra\",\"datePublished\":\"2021-09-10T00:07:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/09\\\/09\\\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\\\/\"},\"wordCount\":158,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/09\\\/09\\\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"pol\u00edtica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/09\\\/09\\\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/09\\\/09\\\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\\\/\",\"url\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/09\\\/09\\\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\\\/\",\"name\":\"Maura Jorge cobra da Caema provid\u00eancias sobre falta de \u00e1gua em bairros de Lago da Pedra - NOT\u00cdCIAS EM TEMPO REAL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/09\\\/09\\\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/09\\\/09\\\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2021-09-10T00:07:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/09\\\/09\\\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/09\\\/09\\\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/09\\\/09\\\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/09\\\/09\\\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/maranhaotv.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Maura Jorge cobra da Caema provid\u00eancias sobre falta de \u00e1gua em bairros de Lago da Pedra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#website\",\"url\":\"https:\\\/\\\/maranhaotv.com.br\\\/\",\"name\":\"Maranh\u00e3oTV\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maranhaotv.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#organization\",\"name\":\"Portal de Not\u00edcias\",\"url\":\"https:\\\/\\\/maranhaotv.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maranhaotv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-cropped-avatar-1.png\",\"contentUrl\":\"https:\\\/\\\/maranhaotv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-cropped-avatar-1.png\",\"width\":792,\"height\":428,\"caption\":\"Portal de Not\u00edcias\"},\"image\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/maiobaotv\",\"https:\\\/\\\/x.com\\\/sitemaranhaotv\",\"https:\\\/\\\/www.instagram.com\\\/maranhao.tv\",\"https:\\\/\\\/www.threads.net\\\/@maranhao.tv\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#\\\/schema\\\/person\\\/3d54238e86b20bb5c89ab2fdb8f8829a\",\"name\":\"maranhaotv\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8fadbca458d4cb68b1dd399ae9a40618d747bb1af65ac9fad21c89220a143eb4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8fadbca458d4cb68b1dd399ae9a40618d747bb1af65ac9fad21c89220a143eb4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8fadbca458d4cb68b1dd399ae9a40618d747bb1af65ac9fad21c89220a143eb4?s=96&d=mm&r=g\",\"caption\":\"maranhaotv\"},\"sameAs\":[\"https:\\\/\\\/maranhaotv.com.br\\\/\"],\"url\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/author\\\/maranhaotv\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maura Jorge cobra da Caema provid\u00eancias sobre falta de \u00e1gua em bairros de Lago da Pedra - NOT\u00cdCIAS EM TEMPO REAL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maranhaotv.com.br\/index.php\/2021\/09\/09\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\/","og_locale":"pt_BR","og_type":"article","og_title":"Maura Jorge cobra da Caema provid\u00eancias sobre falta de \u00e1gua em bairros de Lago da Pedra - NOT\u00cdCIAS EM TEMPO REAL","og_description":"Maura Jorge cobra da Caema A prefeita de Lago da Pedra Maura Jorge vem cobrando providencias da CAEMA, sobre a","og_url":"https:\/\/maranhaotv.com.br\/index.php\/2021\/09\/09\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\/","og_site_name":"NOT\u00cdCIAS EM TEMPO REAL","article_publisher":"https:\/\/www.facebook.com\/maiobaotv","article_published_time":"2021-09-10T00:07:20+00:00","author":"maranhaotv","twitter_card":"summary_large_image","twitter_creator":"@sitemaranhaotv","twitter_site":"@sitemaranhaotv","twitter_misc":{"Escrito por":"maranhaotv","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maranhaotv.com.br\/index.php\/2021\/09\/09\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\/#article","isPartOf":{"@id":"https:\/\/maranhaotv.com.br\/index.php\/2021\/09\/09\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\/"},"author":{"name":"maranhaotv","@id":"https:\/\/maranhaotv.com.br\/#\/schema\/person\/3d54238e86b20bb5c89ab2fdb8f8829a"},"headline":"Maura Jorge cobra da Caema provid\u00eancias sobre falta de \u00e1gua em bairros de Lago da Pedra","datePublished":"2021-09-10T00:07:20+00:00","mainEntityOfPage":{"@id":"https:\/\/maranhaotv.com.br\/index.php\/2021\/09\/09\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\/"},"wordCount":158,"commentCount":0,"publisher":{"@id":"https:\/\/maranhaotv.com.br\/#organization"},"image":{"@id":"https:\/\/maranhaotv.com.br\/index.php\/2021\/09\/09\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\/#primaryimage"},"thumbnailUrl":"","articleSection":["pol\u00edtica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maranhaotv.com.br\/index.php\/2021\/09\/09\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maranhaotv.com.br\/index.php\/2021\/09\/09\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\/","url":"https:\/\/maranhaotv.com.br\/index.php\/2021\/09\/09\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\/","name":"Maura Jorge cobra da Caema provid\u00eancias sobre falta de \u00e1gua em bairros de Lago da Pedra - NOT\u00cdCIAS EM TEMPO REAL","isPartOf":{"@id":"https:\/\/maranhaotv.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maranhaotv.com.br\/index.php\/2021\/09\/09\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\/#primaryimage"},"image":{"@id":"https:\/\/maranhaotv.com.br\/index.php\/2021\/09\/09\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\/#primaryimage"},"thumbnailUrl":"","datePublished":"2021-09-10T00:07:20+00:00","breadcrumb":{"@id":"https:\/\/maranhaotv.com.br\/index.php\/2021\/09\/09\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maranhaotv.com.br\/index.php\/2021\/09\/09\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maranhaotv.com.br\/index.php\/2021\/09\/09\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/maranhaotv.com.br\/index.php\/2021\/09\/09\/maura-jorge-cobra-da-caema-providencias-sobre-falta-de-agua-em-bairros-de-lago-da-pedra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/maranhaotv.com.br\/"},{"@type":"ListItem","position":2,"name":"Maura Jorge cobra da Caema provid\u00eancias sobre falta de \u00e1gua em bairros de Lago da Pedra"}]},{"@type":"WebSite","@id":"https:\/\/maranhaotv.com.br\/#website","url":"https:\/\/maranhaotv.com.br\/","name":"Maranh\u00e3oTV","description":"","publisher":{"@id":"https:\/\/maranhaotv.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maranhaotv.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/maranhaotv.com.br\/#organization","name":"Portal de Not\u00edcias","url":"https:\/\/maranhaotv.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maranhaotv.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/maranhaotv.com.br\/wp-content\/uploads\/2024\/05\/cropped-cropped-avatar-1.png","contentUrl":"https:\/\/maranhaotv.com.br\/wp-content\/uploads\/2024\/05\/cropped-cropped-avatar-1.png","width":792,"height":428,"caption":"Portal de Not\u00edcias"},"image":{"@id":"https:\/\/maranhaotv.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/maiobaotv","https:\/\/x.com\/sitemaranhaotv","https:\/\/www.instagram.com\/maranhao.tv","https:\/\/www.threads.net\/@maranhao.tv"]},{"@type":"Person","@id":"https:\/\/maranhaotv.com.br\/#\/schema\/person\/3d54238e86b20bb5c89ab2fdb8f8829a","name":"maranhaotv","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/8fadbca458d4cb68b1dd399ae9a40618d747bb1af65ac9fad21c89220a143eb4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8fadbca458d4cb68b1dd399ae9a40618d747bb1af65ac9fad21c89220a143eb4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8fadbca458d4cb68b1dd399ae9a40618d747bb1af65ac9fad21c89220a143eb4?s=96&d=mm&r=g","caption":"maranhaotv"},"sameAs":["https:\/\/maranhaotv.com.br\/"],"url":"https:\/\/maranhaotv.com.br\/index.php\/author\/maranhaotv\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=23569"}],"version-history":[{"count":0,"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23569\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=23569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=23569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=23569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}