{"id":24010,"date":"2021-10-01T15:28:01","date_gmt":"2021-10-01T18:28:01","guid":{"rendered":"https:\/\/maranhaotv.com.br\/?p=24010"},"modified":"2021-10-01T15:28:01","modified_gmt":"2021-10-01T18:28:01","slug":"santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao","status":"publish","type":"post","link":"https:\/\/maranhaotv.com.br\/index.php\/2021\/10\/01\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\/","title":{"rendered":"Santa In\u00eas: Felipe dos Pneus vai gastar R$ 144 mil com pesquisa para avaliar sua pr\u00f3pria gest\u00e3o<br>"},"content":{"rendered":"\n<p><em>Depois de tentar aumentar o seu pr\u00f3prio sal\u00e1rio, Felipe dos Pneus surge com essa pesquisa com fortes ind\u00edcios de irregularidades<\/em><br><br>Preocupado com a sua imagem, o prefeito de Santa In\u00eas, Felipe dos Pneus (Republicanos) resolveu contratar uma empresa, atrav\u00e9s da Secretaria de Administra\u00e7\u00e3o do munic\u00edpio, para realizar uma pesquisa de opini\u00e3o p\u00fablica para avaliar sua gest\u00e3o.<br>Em meio \u00e0 pandemia, o prefeito ir\u00e1 pagar a empresa Engracia Garcia Consultoria e Pesquisa Eireli, a bagatela de R$ 144.000,000.<br>De acordo com o levantamento feito pela Folha do Maranh\u00e3o em dados da Receita Federal, a empresa tem como s\u00f3cio-propriet\u00e1rio, o empres\u00e1rio Gerson Engracia Garcia, ex-presidente do Botafogo Futebol Clube. Localizada na cidade de Ribeir\u00e3o Preto, em S\u00e3o Paulo, esse seria o seu primeiro contrato com a administra\u00e7\u00e3o p\u00fablica no Maranh\u00e3o.<br>Recentemente, o Conselho Deliberativo do Botafogo Futebol Clube decidiu expulsar o ex-presidente Gerson Engracia Garcia do quadro de conselheiros. Na reuni\u00e3o, no Est\u00e1dio Santa Cruz, a Assembleia de S\u00f3cios tamb\u00e9m votou por uma a\u00e7\u00e3o indenizat\u00f3ria contra \u201cGersinho\u201d.<br>O ex-presidente \u00e9 acusado de gest\u00e3o temer\u00e1ria por contrato assinado durante a cria\u00e7\u00e3o da empresa Botafogo S\/A, que atualmente gere o futebol da equipe e explora o uso do est\u00e1dio Santa Cruz. <br>Durante o processo licitat\u00f3rio, a prefeitura de Santa In\u00eas realizou uma pesquisa de pre\u00e7o com tr\u00eas empresas: Factual Pesquisas, Escutec e a empresa vencedora, Engracia Garcia Consultoria. N\u00e3o se sabe por qual motivo ou crit\u00e9rio, a chefe de gabinete, Liliane Gatinho Viana, enviou um e-mail solicitando o valor da pesquisa para uma empresa de S\u00e3o Paulo.<br>De acordo com o contrato, est\u00e1 previsto tr\u00eas rodadas de pesquisas, a primeira delas em setembro, outra em dezembro e a \u00faltima em mar\u00e7o do pr\u00f3ximo ano.<br>Do Folha do Maranh\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depois de tentar aumentar o seu pr\u00f3prio sal\u00e1rio, Felipe dos Pneus surge com essa pesquisa com fortes ind\u00edcios de irregularidades<\/p>\n","protected":false},"author":2,"featured_media":24009,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2],"tags":[317,318],"class_list":["post-24010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-felipe-dos-pneus","tag-santa-ines"],"magazineBlocksPostFeaturedMedia":{"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"colormag-highlighted-post":false,"colormag-featured-post-medium":false,"colormag-featured-post-small":false,"colormag-featured-image":false,"colormag-default-news":false,"colormag-featured-image-large":false},"magazineBlocksPostAuthor":{"name":"maranhaotv","avatar":"https:\/\/secure.gravatar.com\/avatar\/8fadbca458d4cb68b1dd399ae9a40618d747bb1af65ac9fad21c89220a143eb4?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":"0","magazineBlocksPostExcerpt":"Depois de tentar aumentar o seu pr\u00f3prio sal\u00e1rio, Felipe dos Pneus surge com essa pesquisa com fortes ind\u00edcios de irregularidades","magazineBlocksPostCategories":["not\u00edcias"],"magazineBlocksPostViewCount":172,"magazineBlocksPostReadTime":2,"magazine_blocks_featured_image_url":{"full":false,"medium":false,"thumbnail":false},"magazine_blocks_author":{"display_name":"maranhaotv","author_link":"https:\/\/maranhaotv.com.br\/index.php\/author\/maranhaotv\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/8fadbca458d4cb68b1dd399ae9a40618d747bb1af65ac9fad21c89220a143eb4?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-2\">not\u00edcias<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Santa In\u00eas: Felipe dos Pneus vai gastar R$ 144 mil com pesquisa para avaliar sua pr\u00f3pria gest\u00e3o - NOT\u00cdCIAS EM TEMPO REAL<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maranhaotv.com.br\/index.php\/2021\/10\/01\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Santa In\u00eas: Felipe dos Pneus vai gastar R$ 144 mil com pesquisa para avaliar sua pr\u00f3pria gest\u00e3o - NOT\u00cdCIAS EM TEMPO REAL\" \/>\n<meta property=\"og:description\" content=\"Depois de tentar aumentar o seu pr\u00f3prio sal\u00e1rio, Felipe dos Pneus surge com essa pesquisa com fortes ind\u00edcios de irregularidades\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maranhaotv.com.br\/index.php\/2021\/10\/01\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\/\" \/>\n<meta property=\"og:site_name\" content=\"NOT\u00cdCIAS EM TEMPO REAL\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/maiobaotv\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-01T18:28:01+00:00\" \/>\n<meta name=\"author\" content=\"maranhaotv\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sitemaranhaotv\" \/>\n<meta name=\"twitter:site\" content=\"@sitemaranhaotv\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"maranhaotv\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/10\\\/01\\\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/10\\\/01\\\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\\\/\"},\"author\":{\"name\":\"maranhaotv\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#\\\/schema\\\/person\\\/3d54238e86b20bb5c89ab2fdb8f8829a\"},\"headline\":\"Santa In\u00eas: Felipe dos Pneus vai gastar R$ 144 mil com pesquisa para avaliar sua pr\u00f3pria gest\u00e3o\",\"datePublished\":\"2021-10-01T18:28:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/10\\\/01\\\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\\\/\"},\"wordCount\":341,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/10\\\/01\\\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Felipe dos Pneus\",\"Santa In\u00eas\"],\"articleSection\":[\"not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/10\\\/01\\\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/10\\\/01\\\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\\\/\",\"url\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/10\\\/01\\\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\\\/\",\"name\":\"Santa In\u00eas: Felipe dos Pneus vai gastar R$ 144 mil com pesquisa para avaliar sua pr\u00f3pria gest\u00e3o - NOT\u00cdCIAS EM TEMPO REAL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/10\\\/01\\\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/10\\\/01\\\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2021-10-01T18:28:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/10\\\/01\\\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/10\\\/01\\\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/10\\\/01\\\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2021\\\/10\\\/01\\\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/maranhaotv.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Santa In\u00eas: Felipe dos Pneus vai gastar R$ 144 mil com pesquisa para avaliar sua pr\u00f3pria gest\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#website\",\"url\":\"https:\\\/\\\/maranhaotv.com.br\\\/\",\"name\":\"Maranh\u00e3oTV\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maranhaotv.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#organization\",\"name\":\"Portal de Not\u00edcias\",\"url\":\"https:\\\/\\\/maranhaotv.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maranhaotv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-cropped-avatar-1.png\",\"contentUrl\":\"https:\\\/\\\/maranhaotv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-cropped-avatar-1.png\",\"width\":792,\"height\":428,\"caption\":\"Portal de Not\u00edcias\"},\"image\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/maiobaotv\",\"https:\\\/\\\/x.com\\\/sitemaranhaotv\",\"https:\\\/\\\/www.instagram.com\\\/maranhao.tv\",\"https:\\\/\\\/www.threads.net\\\/@maranhao.tv\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#\\\/schema\\\/person\\\/3d54238e86b20bb5c89ab2fdb8f8829a\",\"name\":\"maranhaotv\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8fadbca458d4cb68b1dd399ae9a40618d747bb1af65ac9fad21c89220a143eb4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8fadbca458d4cb68b1dd399ae9a40618d747bb1af65ac9fad21c89220a143eb4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8fadbca458d4cb68b1dd399ae9a40618d747bb1af65ac9fad21c89220a143eb4?s=96&d=mm&r=g\",\"caption\":\"maranhaotv\"},\"sameAs\":[\"https:\\\/\\\/maranhaotv.com.br\\\/\"],\"url\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/author\\\/maranhaotv\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Santa In\u00eas: Felipe dos Pneus vai gastar R$ 144 mil com pesquisa para avaliar sua pr\u00f3pria gest\u00e3o - NOT\u00cdCIAS EM TEMPO REAL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maranhaotv.com.br\/index.php\/2021\/10\/01\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\/","og_locale":"pt_BR","og_type":"article","og_title":"Santa In\u00eas: Felipe dos Pneus vai gastar R$ 144 mil com pesquisa para avaliar sua pr\u00f3pria gest\u00e3o - NOT\u00cdCIAS EM TEMPO REAL","og_description":"Depois de tentar aumentar o seu pr\u00f3prio sal\u00e1rio, Felipe dos Pneus surge com essa pesquisa com fortes ind\u00edcios de irregularidades","og_url":"https:\/\/maranhaotv.com.br\/index.php\/2021\/10\/01\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\/","og_site_name":"NOT\u00cdCIAS EM TEMPO REAL","article_publisher":"https:\/\/www.facebook.com\/maiobaotv","article_published_time":"2021-10-01T18:28:01+00:00","author":"maranhaotv","twitter_card":"summary_large_image","twitter_creator":"@sitemaranhaotv","twitter_site":"@sitemaranhaotv","twitter_misc":{"Escrito por":"maranhaotv","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maranhaotv.com.br\/index.php\/2021\/10\/01\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\/#article","isPartOf":{"@id":"https:\/\/maranhaotv.com.br\/index.php\/2021\/10\/01\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\/"},"author":{"name":"maranhaotv","@id":"https:\/\/maranhaotv.com.br\/#\/schema\/person\/3d54238e86b20bb5c89ab2fdb8f8829a"},"headline":"Santa In\u00eas: Felipe dos Pneus vai gastar R$ 144 mil com pesquisa para avaliar sua pr\u00f3pria gest\u00e3o","datePublished":"2021-10-01T18:28:01+00:00","mainEntityOfPage":{"@id":"https:\/\/maranhaotv.com.br\/index.php\/2021\/10\/01\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\/"},"wordCount":341,"commentCount":0,"publisher":{"@id":"https:\/\/maranhaotv.com.br\/#organization"},"image":{"@id":"https:\/\/maranhaotv.com.br\/index.php\/2021\/10\/01\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\/#primaryimage"},"thumbnailUrl":"","keywords":["Felipe dos Pneus","Santa In\u00eas"],"articleSection":["not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maranhaotv.com.br\/index.php\/2021\/10\/01\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maranhaotv.com.br\/index.php\/2021\/10\/01\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\/","url":"https:\/\/maranhaotv.com.br\/index.php\/2021\/10\/01\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\/","name":"Santa In\u00eas: Felipe dos Pneus vai gastar R$ 144 mil com pesquisa para avaliar sua pr\u00f3pria gest\u00e3o - NOT\u00cdCIAS EM TEMPO REAL","isPartOf":{"@id":"https:\/\/maranhaotv.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maranhaotv.com.br\/index.php\/2021\/10\/01\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\/#primaryimage"},"image":{"@id":"https:\/\/maranhaotv.com.br\/index.php\/2021\/10\/01\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\/#primaryimage"},"thumbnailUrl":"","datePublished":"2021-10-01T18:28:01+00:00","breadcrumb":{"@id":"https:\/\/maranhaotv.com.br\/index.php\/2021\/10\/01\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maranhaotv.com.br\/index.php\/2021\/10\/01\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maranhaotv.com.br\/index.php\/2021\/10\/01\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/maranhaotv.com.br\/index.php\/2021\/10\/01\/santa-ines-felipe-dos-pneus-vai-gastar-r-144-mil-com-pesquisa-para-avaliar-sua-propria-gestao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/maranhaotv.com.br\/"},{"@type":"ListItem","position":2,"name":"Santa In\u00eas: Felipe dos Pneus vai gastar R$ 144 mil com pesquisa para avaliar sua pr\u00f3pria gest\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/maranhaotv.com.br\/#website","url":"https:\/\/maranhaotv.com.br\/","name":"Maranh\u00e3oTV","description":"","publisher":{"@id":"https:\/\/maranhaotv.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maranhaotv.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/maranhaotv.com.br\/#organization","name":"Portal de Not\u00edcias","url":"https:\/\/maranhaotv.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maranhaotv.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/maranhaotv.com.br\/wp-content\/uploads\/2024\/05\/cropped-cropped-avatar-1.png","contentUrl":"https:\/\/maranhaotv.com.br\/wp-content\/uploads\/2024\/05\/cropped-cropped-avatar-1.png","width":792,"height":428,"caption":"Portal de Not\u00edcias"},"image":{"@id":"https:\/\/maranhaotv.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/maiobaotv","https:\/\/x.com\/sitemaranhaotv","https:\/\/www.instagram.com\/maranhao.tv","https:\/\/www.threads.net\/@maranhao.tv"]},{"@type":"Person","@id":"https:\/\/maranhaotv.com.br\/#\/schema\/person\/3d54238e86b20bb5c89ab2fdb8f8829a","name":"maranhaotv","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/8fadbca458d4cb68b1dd399ae9a40618d747bb1af65ac9fad21c89220a143eb4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8fadbca458d4cb68b1dd399ae9a40618d747bb1af65ac9fad21c89220a143eb4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8fadbca458d4cb68b1dd399ae9a40618d747bb1af65ac9fad21c89220a143eb4?s=96&d=mm&r=g","caption":"maranhaotv"},"sameAs":["https:\/\/maranhaotv.com.br\/"],"url":"https:\/\/maranhaotv.com.br\/index.php\/author\/maranhaotv\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/posts\/24010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=24010"}],"version-history":[{"count":0,"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/posts\/24010\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=24010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=24010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=24010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}