{"id":34555,"date":"2024-02-06T11:49:34","date_gmt":"2024-02-06T14:49:34","guid":{"rendered":"https:\/\/maranhaotv.com.br\/?p=34555"},"modified":"2024-02-06T11:49:34","modified_gmt":"2024-02-06T14:49:34","slug":"tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar","status":"publish","type":"post","link":"https:\/\/maranhaotv.com.br\/index.php\/2024\/02\/06\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\/","title":{"rendered":"TJMA anula julgamento que absolveu\u00a0homem que matou pastor em Pa\u00e7o do Lumiar"},"content":{"rendered":"\n<p>A 3\u00aa C\u00e2mara Criminal do Tribunal de Justi\u00e7a do Maranh\u00e3o votou de forma favor\u00e1vel \u00e0 apela\u00e7\u00e3o dos assistentes de acusa\u00e7\u00e3o, contra a senten\u00e7a que absolveu Saulo Pereira Nunes da acusa\u00e7\u00e3o dos crimes de homic\u00eddio qualificado e oculta\u00e7\u00e3o de cad\u00e1ver.<br><br>A decis\u00e3o un\u00e2nime foi para anular o julgamento, determinando que o apelado seja submetido a novo julgamento pelo Tribunal do J\u00fari, no Termo Judici\u00e1rio de Pa\u00e7o do Lumiar.<br><br>Segundo o relat\u00f3rio, a den\u00fancia foi de que, tendo descoberto um caso extraconjugal da esposa, Saulo teria acessado um aplicativo dela e, simulando ser a mulher, teria marcado encontro com um homem na casa dela.<br><br>Relata que, em 11 de outubro de 2019, por volta das 13 horas, escondido pr\u00f3ximo \u00e0 lateral do ve\u00edculo estacionado na garagem da resid\u00eancia, teria atingido com golpe de faca o t\u00f3rax da v\u00edtima, que morreu.<br><br>Na sequ\u00eancia, teria enterrado seu corpo em um buraco cavado no quintal e coberto com argamassa de cimento, barro e entulho.<br><br>Em 10 de junho de 2022, o apelado foi pronunciado por homic\u00eddio qualificado e oculta\u00e7\u00e3o de cad\u00e1ver, com fundamento em normas do C\u00f3digo Penal.<br><br>Na Sess\u00e3o do Tribunal do J\u00fari, em 30 de maio de 2023, os jurados, apesar de reconhecerem a materialidade e a autoria do crime de homic\u00eddio, absolveram o apelado no quesito gen\u00e9rico.<br><br>Foram considerados prejudicados os quesitos referentes ao crime de oculta\u00e7\u00e3o de cad\u00e1ver.<br><br>O Minist\u00e9rio P\u00fablico do Estado e os assistentes de acusa\u00e7\u00e3o Tomas David Costa e Ant\u00f4nia da Silva Costa apelaram ao TJMA, contra a senten\u00e7a do Ju\u00edzo da 2\u00aa Vara do Termo Judici\u00e1rio de Pa\u00e7o do Lumiar.<br><br>ARGUMENTOS<br><br>O Minist\u00e9rio P\u00fablico argumentou a ocorr\u00eancia de nulidade absoluta, por considerar que o Conselho de Senten\u00e7a absolveu o apelado apenas em rela\u00e7\u00e3o ao crime de homic\u00eddio, n\u00e3o tendo sido submetidos ao corpo de jurados os quesitos relacionados ao crime de oculta\u00e7\u00e3o de cad\u00e1ver.<br><br>Disse ter sido utilizada a tese da leg\u00edtima defesa da honra, considerada inconstitucional pelo Supremo Tribunal Federal (STF), travestida da tese de relevante valor moral.<br><br>J\u00e1 os assistentes de acusa\u00e7\u00e3o argumentaram que a decis\u00e3o dos jurados foi manifestamente contr\u00e1ria \u00e0 prova dos autos, al\u00e9m de ter sido contradit\u00f3ria, na medida em que absolveu o apelado ao mesmo tempo em que o reconheceu como autor do crime.<br><br>J\u00e1 a defesa do apelado alegou a ocorr\u00eancia de preclus\u00e3o (perda do direito de manifesta\u00e7\u00e3o) da alega\u00e7\u00e3o de nulidade do Minist\u00e9rio P\u00fablico por n\u00e3o terem sido submetidos ao Conselho de Senten\u00e7a os quesitos referentes ao crime conexo de oculta\u00e7\u00e3o de cad\u00e1ver.<br><br>Argumentou que n\u00e3o houve a utiliza\u00e7\u00e3o, em plen\u00e1rio, da tese da leg\u00edtima defesa da honra, e sim da clem\u00eancia, que foi acolhida pelos jurados.<br><br>E entendeu que n\u00e3o houve julgamento contr\u00e1rio \u00e0 prova dos autos, pois a tese acolhida pelos jurados foi a da clem\u00eancia.<br><br>VOTO<br><br>Relatora das apela\u00e7\u00f5es, a desembargadora S\u00f4nia Amaral analisou os recursos e entendeu que n\u00e3o h\u00e1 provas nos autos de que o advogado do apelado tenha utilizado a tese da leg\u00edtima defesa da honra, ainda que de forma indireta, em sua sustenta\u00e7\u00e3o oral na sess\u00e3o do Tribunal do J\u00fari.<br><br>Verificou que, na ata da sess\u00e3o do J\u00fari popular, as teses de defesa foram: desclassifica\u00e7\u00e3o, clem\u00eancia, privil\u00e9gio para relevante valor moral e afastamento das qualificadoras.<br><br>Com isso, n\u00e3o acolheu a alega\u00e7\u00e3o do Minist\u00e9rio P\u00fablico.<br><br>VIABILIDADE<br><br>Em rela\u00e7\u00e3o ao segundo apelo, dos assistentes de acusa\u00e7\u00e3o, a relatora entendeu pela viabilidade de se reformar a decis\u00e3o soberana que absolveu o r\u00e9u, por contrariedade manifesta \u00e0 prova dos autos.<br><br>Ressaltou que, ao analis\u00e1-los de forma detida, verificou que os pr\u00f3prios jurados responderam afirmativamente \u00e0s indaga\u00e7\u00f5es acerca da materialidade e da autoria dos delitos em rela\u00e7\u00e3o ao crime de homic\u00eddio.<br><br>\u201cOu seja, de acordo com o entendimento dos jurados, as provas colacionadas nos autos n\u00e3o deixam d\u00favidas de que o apelado efetivamente praticou o crime de homic\u00eddio nos termos narrados pelo Minist\u00e9rio P\u00fablico na pe\u00e7a acusat\u00f3ria\u201d, frisou a desembargadora S\u00f4nia Amaral.<br><br>Afirmou que, dentre as teses de defesa apresentadas pelo advogado do apelado na sess\u00e3o de julgamento (desclassifica\u00e7\u00e3o, clem\u00eancia, privil\u00e9gio para relevante valor moral e afastamento das qualificadoras), a \u00fanica que poderia conduzir \u00e0 sua absolvi\u00e7\u00e3o seria a de clem\u00eancia.<br><br>CONTROV\u00c9RSIA<br><br>A desembargadora lembrou que existe uma controv\u00e9rsia nos tribunais superiores acerca da possibilidade de o tribunal de segunda inst\u00e2ncia anular o julgamento do Tribunal do J\u00fari com fundamento no artigo 593, inciso III \u201cd\u201d, do C\u00f3digo de Processo Penal (ou seja, quando a decis\u00e3o \u00e9 manifestamente contr\u00e1ria \u00e0 prova dos autos) nas hip\u00f3teses em que os jurados reconhecem a materialidade e autorias delitivas, mas absolvem o acusado com base exclusivamente no pedido de clem\u00eancia feito.<br><br>Disse que nem mesmo no pr\u00f3prio STF h\u00e1 um entendimento pacificado sobre a quest\u00e3o, citando duas decis\u00f5es opostas em julgamentos da Suprema Corte.<br><br>A relatora citou e concordou com entendimento da Terceira Se\u00e7\u00e3o do Superior Tribunal de Justi\u00e7a, segundo a qual, \u201ca absolvi\u00e7\u00e3o do r\u00e9u pelos jurados, com base no art. 483, III, do CPP, ainda que por clem\u00eancia, n\u00e3o constitui decis\u00e3o absoluta e irrevog\u00e1vel, podendo o Tribunal cassar tal decis\u00e3o quando ficar demonstrada a total dissocia\u00e7\u00e3o da conclus\u00e3o dos jurados com as provas apresentadas em plen\u00e1rio\u201d.<br><br>No caso analisado, a desembargadora S\u00f4nia disse que o pr\u00f3prio Conselho de Senten\u00e7a reconheceu a materialidade do crime de homic\u00eddio e comprovada, de forma indiscut\u00edvel, a autoria do delito, at\u00e9 porque n\u00e3o foi apresentada a tese de negativa de autoria, e o apelado, inclusive, confessou a pr\u00e1tica do ato, apenas trazendo como justificativa t\u00ea-lo cometido \u201cimpelido por motivo de relevante valor moral\u201d.<br><br>Concluiu que, em raz\u00e3o da anula\u00e7\u00e3o do julgamento, perde o objeto a alega\u00e7\u00e3o de nulidade que consta no apelo do Minist\u00e9rio P\u00fablico, por terem sido considerados prejudicados os quesitos referentes ao crime conexo de oculta\u00e7\u00e3o de cad\u00e1ver.<br><br>Os desembargadores Vicente de Castro e Sebasti\u00e3o Bonfim concordaram com o voto da relatora.<br><br>A 3\u00aa C\u00e2mara Criminal passou a contar com a presen\u00e7a do desembargador Nilo Ribeiro Filho (primeiro \u00e0 esquerda na foto abaixo) \u2013 que n\u00e3o participou deste julgamento \u2013, eleito e empossado no cargo de desembargador, pelo crit\u00e9rio de merecimento, no dia 24 de janeiro passado.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/maranhaotv.com.br\/wp-content\/uploads\/2024\/02\/Julgamento-na-3a-Camara-Criminal-300x200.jpg\" alt=\"\" class=\"wp-image-34553\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>A 3\u00aa C\u00e2mara Criminal do Tribunal de Justi\u00e7a do Maranh\u00e3o votou de forma favor\u00e1vel \u00e0 apela\u00e7\u00e3o dos assistentes de acusa\u00e7\u00e3o,<\/p>\n","protected":false},"author":2,"featured_media":34554,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-34555","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policial"],"magazineBlocksPostFeaturedMedia":{"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"colormag-highlighted-post":false,"colormag-featured-post-medium":false,"colormag-featured-post-small":false,"colormag-featured-image":false,"colormag-default-news":false,"colormag-featured-image-large":false},"magazineBlocksPostAuthor":{"name":"maranhaotv","avatar":"https:\/\/secure.gravatar.com\/avatar\/8fadbca458d4cb68b1dd399ae9a40618d747bb1af65ac9fad21c89220a143eb4?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":"0","magazineBlocksPostExcerpt":"A 3\u00aa C\u00e2mara Criminal do Tribunal de Justi\u00e7a do Maranh\u00e3o votou de forma favor\u00e1vel \u00e0 apela\u00e7\u00e3o dos assistentes de acusa\u00e7\u00e3o,","magazineBlocksPostCategories":["policial"],"magazineBlocksPostViewCount":268,"magazineBlocksPostReadTime":6,"magazine_blocks_featured_image_url":{"full":false,"medium":false,"thumbnail":false},"magazine_blocks_author":{"display_name":"maranhaotv","author_link":"https:\/\/maranhaotv.com.br\/index.php\/author\/maranhaotv\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/8fadbca458d4cb68b1dd399ae9a40618d747bb1af65ac9fad21c89220a143eb4?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-3\">policial<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TJMA anula julgamento que absolveu\u00a0homem que matou pastor em Pa\u00e7o do Lumiar - NOT\u00cdCIAS EM TEMPO REAL<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maranhaotv.com.br\/index.php\/2024\/02\/06\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TJMA anula julgamento que absolveu\u00a0homem que matou pastor em Pa\u00e7o do Lumiar - NOT\u00cdCIAS EM TEMPO REAL\" \/>\n<meta property=\"og:description\" content=\"A 3\u00aa C\u00e2mara Criminal do Tribunal de Justi\u00e7a do Maranh\u00e3o votou de forma favor\u00e1vel \u00e0 apela\u00e7\u00e3o dos assistentes de acusa\u00e7\u00e3o,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maranhaotv.com.br\/index.php\/2024\/02\/06\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\/\" \/>\n<meta property=\"og:site_name\" content=\"NOT\u00cdCIAS EM TEMPO REAL\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/maiobaotv\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-06T14:49:34+00:00\" \/>\n<meta name=\"author\" content=\"maranhaotv\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sitemaranhaotv\" \/>\n<meta name=\"twitter:site\" content=\"@sitemaranhaotv\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"maranhaotv\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2024\\\/02\\\/06\\\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2024\\\/02\\\/06\\\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\\\/\"},\"author\":{\"name\":\"maranhaotv\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#\\\/schema\\\/person\\\/3d54238e86b20bb5c89ab2fdb8f8829a\"},\"headline\":\"TJMA anula julgamento que absolveu\u00a0homem que matou pastor em Pa\u00e7o do Lumiar\",\"datePublished\":\"2024-02-06T14:49:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2024\\\/02\\\/06\\\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\\\/\"},\"wordCount\":1153,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2024\\\/02\\\/06\\\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"policial\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2024\\\/02\\\/06\\\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2024\\\/02\\\/06\\\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\\\/\",\"url\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2024\\\/02\\\/06\\\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\\\/\",\"name\":\"TJMA anula julgamento que absolveu\u00a0homem que matou pastor em Pa\u00e7o do Lumiar - NOT\u00cdCIAS EM TEMPO REAL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2024\\\/02\\\/06\\\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2024\\\/02\\\/06\\\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2024-02-06T14:49:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2024\\\/02\\\/06\\\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2024\\\/02\\\/06\\\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2024\\\/02\\\/06\\\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/2024\\\/02\\\/06\\\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/maranhaotv.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TJMA anula julgamento que absolveu\u00a0homem que matou pastor em Pa\u00e7o do Lumiar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#website\",\"url\":\"https:\\\/\\\/maranhaotv.com.br\\\/\",\"name\":\"Maranh\u00e3oTV\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maranhaotv.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#organization\",\"name\":\"Portal de Not\u00edcias\",\"url\":\"https:\\\/\\\/maranhaotv.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maranhaotv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-cropped-avatar-1.png\",\"contentUrl\":\"https:\\\/\\\/maranhaotv.com.br\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-cropped-avatar-1.png\",\"width\":792,\"height\":428,\"caption\":\"Portal de Not\u00edcias\"},\"image\":{\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/maiobaotv\",\"https:\\\/\\\/x.com\\\/sitemaranhaotv\",\"https:\\\/\\\/www.instagram.com\\\/maranhao.tv\",\"https:\\\/\\\/www.threads.net\\\/@maranhao.tv\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/maranhaotv.com.br\\\/#\\\/schema\\\/person\\\/3d54238e86b20bb5c89ab2fdb8f8829a\",\"name\":\"maranhaotv\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8fadbca458d4cb68b1dd399ae9a40618d747bb1af65ac9fad21c89220a143eb4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8fadbca458d4cb68b1dd399ae9a40618d747bb1af65ac9fad21c89220a143eb4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8fadbca458d4cb68b1dd399ae9a40618d747bb1af65ac9fad21c89220a143eb4?s=96&d=mm&r=g\",\"caption\":\"maranhaotv\"},\"sameAs\":[\"https:\\\/\\\/maranhaotv.com.br\\\/\"],\"url\":\"https:\\\/\\\/maranhaotv.com.br\\\/index.php\\\/author\\\/maranhaotv\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TJMA anula julgamento que absolveu\u00a0homem que matou pastor em Pa\u00e7o do Lumiar - NOT\u00cdCIAS EM TEMPO REAL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maranhaotv.com.br\/index.php\/2024\/02\/06\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\/","og_locale":"pt_BR","og_type":"article","og_title":"TJMA anula julgamento que absolveu\u00a0homem que matou pastor em Pa\u00e7o do Lumiar - NOT\u00cdCIAS EM TEMPO REAL","og_description":"A 3\u00aa C\u00e2mara Criminal do Tribunal de Justi\u00e7a do Maranh\u00e3o votou de forma favor\u00e1vel \u00e0 apela\u00e7\u00e3o dos assistentes de acusa\u00e7\u00e3o,","og_url":"https:\/\/maranhaotv.com.br\/index.php\/2024\/02\/06\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\/","og_site_name":"NOT\u00cdCIAS EM TEMPO REAL","article_publisher":"https:\/\/www.facebook.com\/maiobaotv","article_published_time":"2024-02-06T14:49:34+00:00","author":"maranhaotv","twitter_card":"summary_large_image","twitter_creator":"@sitemaranhaotv","twitter_site":"@sitemaranhaotv","twitter_misc":{"Escrito por":"maranhaotv","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/maranhaotv.com.br\/index.php\/2024\/02\/06\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\/#article","isPartOf":{"@id":"https:\/\/maranhaotv.com.br\/index.php\/2024\/02\/06\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\/"},"author":{"name":"maranhaotv","@id":"https:\/\/maranhaotv.com.br\/#\/schema\/person\/3d54238e86b20bb5c89ab2fdb8f8829a"},"headline":"TJMA anula julgamento que absolveu\u00a0homem que matou pastor em Pa\u00e7o do Lumiar","datePublished":"2024-02-06T14:49:34+00:00","mainEntityOfPage":{"@id":"https:\/\/maranhaotv.com.br\/index.php\/2024\/02\/06\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\/"},"wordCount":1153,"commentCount":0,"publisher":{"@id":"https:\/\/maranhaotv.com.br\/#organization"},"image":{"@id":"https:\/\/maranhaotv.com.br\/index.php\/2024\/02\/06\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\/#primaryimage"},"thumbnailUrl":"","articleSection":["policial"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/maranhaotv.com.br\/index.php\/2024\/02\/06\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/maranhaotv.com.br\/index.php\/2024\/02\/06\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\/","url":"https:\/\/maranhaotv.com.br\/index.php\/2024\/02\/06\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\/","name":"TJMA anula julgamento que absolveu\u00a0homem que matou pastor em Pa\u00e7o do Lumiar - NOT\u00cdCIAS EM TEMPO REAL","isPartOf":{"@id":"https:\/\/maranhaotv.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maranhaotv.com.br\/index.php\/2024\/02\/06\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\/#primaryimage"},"image":{"@id":"https:\/\/maranhaotv.com.br\/index.php\/2024\/02\/06\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\/#primaryimage"},"thumbnailUrl":"","datePublished":"2024-02-06T14:49:34+00:00","breadcrumb":{"@id":"https:\/\/maranhaotv.com.br\/index.php\/2024\/02\/06\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maranhaotv.com.br\/index.php\/2024\/02\/06\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maranhaotv.com.br\/index.php\/2024\/02\/06\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/maranhaotv.com.br\/index.php\/2024\/02\/06\/tjma-anula-julgamento-que-absolveu-homem-que-matou-pastor-em-paco-do-lumiar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/maranhaotv.com.br\/"},{"@type":"ListItem","position":2,"name":"TJMA anula julgamento que absolveu\u00a0homem que matou pastor em Pa\u00e7o do Lumiar"}]},{"@type":"WebSite","@id":"https:\/\/maranhaotv.com.br\/#website","url":"https:\/\/maranhaotv.com.br\/","name":"Maranh\u00e3oTV","description":"","publisher":{"@id":"https:\/\/maranhaotv.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maranhaotv.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/maranhaotv.com.br\/#organization","name":"Portal de Not\u00edcias","url":"https:\/\/maranhaotv.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/maranhaotv.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/maranhaotv.com.br\/wp-content\/uploads\/2024\/05\/cropped-cropped-avatar-1.png","contentUrl":"https:\/\/maranhaotv.com.br\/wp-content\/uploads\/2024\/05\/cropped-cropped-avatar-1.png","width":792,"height":428,"caption":"Portal de Not\u00edcias"},"image":{"@id":"https:\/\/maranhaotv.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/maiobaotv","https:\/\/x.com\/sitemaranhaotv","https:\/\/www.instagram.com\/maranhao.tv","https:\/\/www.threads.net\/@maranhao.tv"]},{"@type":"Person","@id":"https:\/\/maranhaotv.com.br\/#\/schema\/person\/3d54238e86b20bb5c89ab2fdb8f8829a","name":"maranhaotv","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/8fadbca458d4cb68b1dd399ae9a40618d747bb1af65ac9fad21c89220a143eb4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8fadbca458d4cb68b1dd399ae9a40618d747bb1af65ac9fad21c89220a143eb4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8fadbca458d4cb68b1dd399ae9a40618d747bb1af65ac9fad21c89220a143eb4?s=96&d=mm&r=g","caption":"maranhaotv"},"sameAs":["https:\/\/maranhaotv.com.br\/"],"url":"https:\/\/maranhaotv.com.br\/index.php\/author\/maranhaotv\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/posts\/34555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=34555"}],"version-history":[{"count":0,"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/posts\/34555\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=34555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=34555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maranhaotv.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=34555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}